{"id":13489,"date":"2024-09-04T17:09:26","date_gmt":"2024-09-04T17:09:26","guid":{"rendered":"https:\/\/www.isocfoundation.org\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/"},"modified":"2026-02-11T17:04:51","modified_gmt":"2026-02-11T17:04:51","slug":"el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal","status":"publish","type":"story","link":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/","title":{"rendered":"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Brasil es conocido por su compleja burocracia y los malentendidos o intentos de evitarla han dejado a muchas redes comunitarias operando de manera irregular o incluso ilegal. Como resultado, muchos temen ser clasificados como &#171;servicios clandestinos de telecomunicaciones&#187;, lo que puede acarrear multas de 10.000 reales (1.790 d\u00f3lares) o penas de prisi\u00f3n de dos a cuatro a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una red comunitaria es una soluci\u00f3n de acceso a Internet construida y administrada por una comunidad, en lugar de a trav\u00e9s de un proveedor de servicios de Internet importante, que ofrece una forma de cerrar la brecha digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#171;Operar sin los permisos adecuados puede dejar a las redes comunitarias vulnerables a la opresi\u00f3n pol\u00edtica o a acusaciones oportunistas&#187;, explica Marcelo Saldanha, presidente del Instituto Bem Estar (IBE) de Brasil.<\/p>\n\n\n\n<figure class=\"wp-block-image tb-image tb-image-media tb-image-frame-none\" data-toolset-blocks-image=\"9c74036ea69fd541b3eb6bebef05ef3c\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/06\/brazilcn2-e1624530916966.jpg\" alt=\"two men standing in a wide grassy field\" class=\"wp-image-4966\"\/><figcaption><div class=\"tb-image-caption\">Wagner Crespo, (en primer plano), con un colega que ayud\u00f3 a establecer la red comunitaria en Esp\u00edritu Santinho. <br\/>Foto cortes\u00eda de Wagner Crespo.<\/div><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Saldanha fue el instructor principal de un novedoso curso sobre cuestiones regulatorias y pol\u00edticas p\u00fablicas que afectan a las redes comunitarias, encargado por el Cap\u00edtulo Brasil de Internet Society y financiado con una <a href=\"https:\/\/www.isocfoundation.org\/es\/grant-programme\/programa-de-subvenciones-pequenas-beyond-the-net\/\">peque\u00f1a subvenci\u00f3n de 2020<\/a> para $US 3.500 de la fundaci\u00f3n Internet Society. Diecinueve representantes de una docena de redes comunitarias completaron el curso en l\u00ednea de 32 horas en octubre-noviembre de 2020.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ahora entienden c\u00f3mo funciona Anatel [la Agencia Nacional de Telecomunicaciones de Brasil] y c\u00f3mo interpretar correctamente documentos que est\u00e1n escritos en t\u00e9rminos legales y t\u00e9cnicos con referencias a leyes y decretos. Es importante que las redes comunitarias obtengan esta informaci\u00f3n pr\u00e1ctica y hay apertura por parte de ANATEL para reconocer las redes comunitarias&#187;.<\/p>\n<cite>Fl\u00e1vio Rech Wagner, presidente del Cap\u00edtulo Brasil de Internet Society y profesor de la Universidad Federal de Rio Grande do Sul.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado de la capacitaci\u00f3n, seis redes comunitarias iniciaron el proceso de registro oficial en diciembre, solicitando licencias a ANATEL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre ellos se encontraba Wagner Crespo, un ingeniero que ayud\u00f3 a establecer una red comunitaria como voluntario en el barrio de Esp\u00edrito Santinho, municipio de Campos, en el estado de R\u00edo de Janeiro, en diciembre de 2019.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"639\" src=\"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/07\/brazil-project-map-2.png\" alt=\"Mapa de Brasil, que muestra la ubicaci\u00f3n de Esp\u00edrito Santinho en Campos\" class=\"wp-image-5036\" srcset=\"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/07\/brazil-project-map-2.png 1000w, https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/07\/brazil-project-map-2-300x192.png 300w, https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/07\/brazil-project-map-2-768x491.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Mapa de Brasil, que muestra la ubicaci\u00f3n de Esp\u00edrito Santinho en Campos<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#171;No nos legalizamos con Anatel porque el proceso es muy complicado, pero el curso nos ayud\u00f3 a hacer las cosas de la manera correcta&#187;, dice Crespo. &#171;Esto fue muy importante porque en Brasil hay muchas personas que trabajan por el bien social, pero si hacen algo un poco mal, tal vez por falta de conocimiento, pueden ser crucificados&#187;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nos preocupaba que la comunidad con la que nos hab\u00edamos conectado pudiera sufrir si algo sal\u00eda mal. Era una gran preocupaci\u00f3n para nosotros, pero no sab\u00edamos ni por d\u00f3nde empezar a legalizar la red, ni d\u00f3nde encontrar esa informaci\u00f3n. Si no hubiera sido por este curso, todav\u00eda estar\u00edamos viviendo con miedo&#187;.<\/p>\n<cite>Wagner Crespo<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La &#171;regularizaci\u00f3n&#187; tambi\u00e9n permitir\u00e1 a los administradores de redes comunitarias solicitar subvenciones o financiaci\u00f3n y participar en programas p\u00fablicos. En muchos casos, este tipo de financiaci\u00f3n requiere que las redes est\u00e9n registradas legalmente o, al menos, favorecer\u00eda a las que s\u00ed lo est\u00e1n, dice Saldanha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las seis redes que se postularon han obtenido la primera de dos autorizaciones: para ofrecer servicios. El segundo, para el uso del espectro, a\u00fan est\u00e1 pendiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra de estas solicitantes iniciales fue Bruna Zanolli, una tecn\u00f3loga de inter\u00e9s p\u00fablico de 33 a\u00f1os que ha ayudado a establecer seis redes comunitarias diferentes, la \u00faltima de las cuales se encuentra en una comunidad anteriormente esclavizada (<em>quilombo<\/em>) en el estado de S\u00e3o Paulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#171;Quer\u00eda hacer el proceso yo misma antes de decirle a la comunidad c\u00f3mo hacerlo&#187;, dice. Tambi\u00e9n le ayud\u00f3 a elaborar una peque\u00f1a gu\u00eda introductoria para las comunidades que est\u00e1n interesadas en iniciar una red comunitaria. &#171;Le pregunt\u00e9 a la comunidad y quer\u00edan regularizar. Como son <em>quilombo<\/em>, sus tierras son propiedad del Estado y no quieren que ocurra en su territorio nada contrario a la ley o incluso remotamente cuestionable desde el punto de vista legal o que ponga en riesgo su CN&#187;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#171;Para m\u00ed, este curso tambi\u00e9n se trataba de conocer el estado m\u00e1s reciente de nuestra legislaci\u00f3n y Marcelo es una enciclopedia humana para eso&#187;, agrega Zanolli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quer\u00eda conocer la ley para ayudar a cambiar la ley, eventualmente, especialmente para beneficiar a las comunidades ind\u00edgenas y quilombolas y a las poblaciones que hist\u00f3ricamente han estado en desventaja&#187;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo, IBEBrasil, ISOC Brasil, la Asociaci\u00f3n para el Progreso de las Comunicaciones y otros defensores de las redes comunitarias han estado presionando por un cambio en las leyes y regulaciones existentes desde 2008, ya sea para eliminar la burocracia y\/o para simplificarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#171;Las pol\u00edticas digitales de Brasil est\u00e1n tan desconectadas que es como si estuvieran hechas para no funcionar&#187;, bromea Saldanha. Pero ANATEL ha anunciado que pronto simplificar\u00e1 las regulaciones para beneficiar a las redes comunitarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el grupo inicial de seis, otros dos participantes del curso han comenzado a reunir documentaci\u00f3n para presentar solicitudes, mientras que los cuatro restantes todav\u00eda est\u00e1n en conversaciones con sus comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#171;IBEBrasil imparti\u00f3 una formaci\u00f3n muy concreta sobre c\u00f3mo navegar por la burocracia de Anatel y qu\u00e9 documentos necesitan rellenar&#187;, dice Wagner. &#171;Si trataran de resolverlo por s\u00ed mismos, podr\u00eda llevar mucho tiempo o podr\u00edan hacer lo incorrecto, por lo que esto tambi\u00e9n es una especie de empoderamiento&#187;.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.isocfoundation.org\/es\/programas-de-subvenciones\/\">M\u00e1s informaci\u00f3n sobre nuestras subvenciones\/becas<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brasil es famoso por su compleja burocracia y los malentendidos o intentos de evitarla han dejado a muchas redes comunitarias operando de manera irregular o incluso ilegal. <\/p>\n","protected":false},"featured_media":4983,"template":"","categories":[],"tags":[],"programme-area":[],"class_list":["post-13489","story","type-story","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal | Internet Society Foundation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal | Internet Society Foundation\" \/>\n<meta property=\"og:description\" content=\"Brasil es famoso por su compleja burocracia y los malentendidos o intentos de evitarla han dejado a muchas redes comunitarias operando de manera irregular o incluso ilegal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Internet Society Foundation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T17:04:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/06\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ISOC_Foundation\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/\",\"name\":\"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal | Internet Society Foundation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg\",\"datePublished\":\"2024-09-04T17:09:26+00:00\",\"dateModified\":\"2026-02-11T17:04:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg\",\"width\":1600,\"height\":898,\"caption\":\"Photo by Diego Carneiro on Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/story\\\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.isocfoundation.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stories\",\"item\":\"https:\\\/\\\/www.isocfoundation.org\\\/story\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#website\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/\",\"name\":\"Internet Society Foundation\",\"description\":\"The Internet transforms lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.isocfoundation.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#organization\",\"name\":\"Internet Society Foundation\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/internet-society-foundation.jpg\",\"contentUrl\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/internet-society-foundation.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Internet Society Foundation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ISOC_Foundation\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal | Internet Society Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/","og_locale":"es_ES","og_type":"article","og_title":"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal | Internet Society Foundation","og_description":"Brasil es famoso por su compleja burocracia y los malentendidos o intentos de evitarla han dejado a muchas redes comunitarias operando de manera irregular o incluso ilegal.","og_url":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/","og_site_name":"Internet Society Foundation","article_modified_time":"2026-02-11T17:04:51+00:00","og_image":[{"width":1600,"height":898,"url":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/06\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ISOC_Foundation","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/","url":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/","name":"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal | Internet Society Foundation","isPartOf":{"@id":"https:\/\/www.isocfoundation.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/#primaryimage"},"image":{"@id":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/06\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg","datePublished":"2024-09-04T17:09:26+00:00","dateModified":"2026-02-11T17:04:51+00:00","breadcrumb":{"@id":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/#primaryimage","url":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/06\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg","contentUrl":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2021\/06\/diego-carneiro-JesYw3Z-vHk-unsplash.jpeg","width":1600,"height":898,"caption":"Photo by Diego Carneiro on Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.isocfoundation.org\/es\/story\/el-curso-guia-a-las-redes-comunitarias-brasilenas-sobre-como-obtener-reconocimiento-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.isocfoundation.org\/es\/"},{"@type":"ListItem","position":2,"name":"Stories","item":"https:\/\/www.isocfoundation.org\/story\/"},{"@type":"ListItem","position":3,"name":"El curso gu\u00eda a las redes comunitarias brasile\u00f1as sobre c\u00f3mo obtener reconocimiento legal"}]},{"@type":"WebSite","@id":"https:\/\/www.isocfoundation.org\/#website","url":"https:\/\/www.isocfoundation.org\/","name":"Internet Society Foundation","description":"The Internet transforms lives","publisher":{"@id":"https:\/\/www.isocfoundation.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.isocfoundation.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.isocfoundation.org\/#organization","name":"Internet Society Foundation","url":"https:\/\/www.isocfoundation.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.isocfoundation.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2019\/02\/internet-society-foundation.jpg","contentUrl":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2019\/02\/internet-society-foundation.jpg","width":1200,"height":630,"caption":"Internet Society Foundation"},"image":{"@id":"https:\/\/www.isocfoundation.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ISOC_Foundation"]}]}},"_links":{"self":[{"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/story\/13489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/types\/story"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/media\/4983"}],"wp:attachment":[{"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/media?parent=13489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/categories?post=13489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/tags?post=13489"},{"taxonomy":"programme-area","embeddable":true,"href":"https:\/\/www.isocfoundation.org\/es\/wp-json\/wp\/v2\/programme-area?post=13489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}