{"id":20827,"date":"2026-03-24T09:46:03","date_gmt":"2026-03-24T09:46:03","guid":{"rendered":"https:\/\/www.isocfoundation.org\/?post_type=grant-programme&#038;p=20827"},"modified":"2026-08-19T19:56:01","modified_gmt":"2026-08-19T19:56:01","slug":"evenements-de-la-journee-mondiale-du-chiffrement","status":"publish","type":"grant-programme","link":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/","title":{"rendered":"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le financement des \u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement par la Fondation Internet Society soutient des activit\u00e9s men\u00e9es par la communaut\u00e9, qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout, un pilier essentiel d\u2019un Internet s\u00fbr et digne de confiance. Chaque ann\u00e9e, la Journ\u00e9e mondiale du chiffrement a lieu le 21 octobre et rassemble la soci\u00e9t\u00e9 civile, les technologues, les entreprises et les utilisateurs d\u2019Internet afin de promouvoir, prot\u00e9ger et d\u00e9fendre un chiffrement fort.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez examiner attentivement la description de ce programme. Les d\u00e9tails du programme (y compris le calendrier, les crit\u00e8res d\u2019\u00e9ligibilit\u00e9 et les \u00e9tapes de candidature) peuvent \u00eatre mis \u00e0 jour chaque ann\u00e9e.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Objectifs du programme<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Soutenir les efforts visant \u00e0 promouvoir et \u00e0 d\u00e9fendre un chiffrement fort de bout en bout comme mesure de protection concr\u00e8te pour les personnes et les communaut\u00e9s en ligne.<\/li>\n\n\n\n<li>Aider le public \u00e0 mieux comprendre l\u2019importance du chiffrement pour la confidentialit\u00e9, la s\u00e9curit\u00e9 et la confiance dans l\u2019environnement num\u00e9rique.<\/li>\n\n\n\n<li>Cr\u00e9er une dynamique autour de la Journ\u00e9e mondiale du chiffrement en aidant les organisateurs locaux et r\u00e9gionaux \u00e0 mobiliser leurs communaut\u00e9s, \u00e0 mettre en avant les perspectives locales et \u00e0 amplifier le message politique de la Journ\u00e9e, en appelant les gouvernements \u00e0 prot\u00e9ger et \u00e0 renforcer le chiffrement, et \u00e0 \u00e9viter toute mesure qui l\u2019affaiblirait et compromettrait la s\u00e9curit\u00e9 d\u2019Internet.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Domaines d\u2019int\u00e9r\u00eat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation finance des activit\u00e9s qui soutiennent et c\u00e9l\u00e8brent la Journ\u00e9e mondiale du chiffrement, notamment des \u00e9v\u00e9nements et des rencontres qui :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Encouragent l\u2019adoption et l\u2019utilisation d\u2019outils et de services chiffr\u00e9s de bout en bout.<\/li>\n\n\n\n<li>Aident les communaut\u00e9s \u00e0 comprendre les risques r\u00e9els li\u00e9s aux propositions politiques qui affaiblissent le chiffrement.<\/li>\n\n\n\n<li>Rassemblent les parties prenantes (soci\u00e9t\u00e9 civile, communaut\u00e9 technique, d\u00e9cideurs politiques, \u00e9ducateurs, journalistes, etc.) pour discuter de la mani\u00e8re dont un chiffrement fort prot\u00e8ge les personnes en p\u00e9riode d\u2019incertitude.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9ligibilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce financement est destin\u00e9 aux organisations qui pr\u00e9voient une activit\u00e9 en accord avec la Journ\u00e9e mondiale du chiffrement et avec les objectifs et les messages de la Coalition mondiale pour le chiffrement (Global Encryption Coalition).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez prendre note des \u00e9l\u00e9ments suivants requis pour \u00eatre \u00e9ligible :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les candidatures sont ouvertes aux particuliers ou aux organisations membres de la Coalition mondiale pour le chiffrement \u00e0 partir du 22 juin 2026.<\/li>\n\n\n\n<li>Les activit\u00e9s doivent \u00eatre planifi\u00e9es autour de la Journ\u00e9e mondiale du chiffrement (21 octobre) et inclure des programmes durant la p\u00e9riode sp\u00e9cifi\u00e9e dans l\u2019appel annuel. Les \u00e9v\u00e9nements peuvent se tenir jusqu\u2019\u00e0 quatre semaines avant ou apr\u00e8s le 21 octobre, en consid\u00e9rant que des engagements significatifs durent souvent plus d\u2019une seule journ\u00e9e.<\/li>\n\n\n\n<li>Les particuliers et les organisations candidats doivent accorder une attention particuli\u00e8re aux besoins en mati\u00e8re de localisation, d\u2019accessibilit\u00e9 et d\u2019inclusion dans les activit\u00e9s qu\u2019ils proposent. Cela inclut la production de supports et la diffusion de contenus dans les langues locales, ainsi que l\u2019utilisation de services de sous-titrage et\/ou d\u2019interpr\u00e9tation. Veuillez consulter les notes sur l\u2019accessibilit\u00e9 ci-dessous.<\/li>\n\n\n\n<li>Les subventions sont limit\u00e9es \u00e0 une subvention par organisation et par cycle.<\/li>\n\n\n\n<li>Les candidats doivent disposer d\u2019un compte bancaire officiel pouvant recevoir des fonds d\u2019une entit\u00e9 am\u00e9ricaine au nom de l\u2019organisation candidate.<\/li>\n\n\n\n<li>Les b\u00e9n\u00e9ficiaires doivent accepter les exigences de base en mati\u00e8re de d\u00e9claration via le syst\u00e8me de gestion des financements de la Fondation (Fluxx).<\/li>\n\n\n\n<li>Les b\u00e9n\u00e9ficiaires doivent en g\u00e9n\u00e9ral consentir \u00e0 l\u2019inscription de l\u2019\u00e9v\u00e9nement au calendrier principal de la Coalition mondiale pour le chiffrement, sauf si l\u2019\u00e9v\u00e9nement est \u00e0 huis clos\/priv\u00e9.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Processus d\u2019examen des demandes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les candidatures sont examin\u00e9es par le personnel de la Fondation Internet Society afin de d\u00e9terminer si elles r\u00e9pondent aux crit\u00e8res d\u2019\u00e9ligibilit\u00e9 et s\u2019inscrivent dans le domaine d\u2019int\u00e9r\u00eat du programme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crit\u00e8res de s\u00e9lection<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les crit\u00e8res de s\u00e9lection utilis\u00e9s pour \u00e9valuer les candidatures \u00e9ligibles sont les suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les activit\u00e9s propos\u00e9es soutiennent les objectifs du programme et sont en ad\u00e9quation avec la Journ\u00e9e mondiale du chiffrement.<\/li>\n\n\n\n<li>L\u2019activit\u00e9 propos\u00e9e r\u00e9pond aux crit\u00e8res d\u2019\u00e9ligibilit\u00e9 d\u00e9crits dans l\u2019appel annuel.<\/li>\n\n\n\n<li>Le particulier ou l\u2019organisation qui postule peut prouver avoir les connaissances et l\u2019exp\u00e9rience n\u00e9cessaires pour r\u00e9aliser l\u2019activit\u00e9 telle que propos\u00e9e.<\/li>\n\n\n\n<li>Si le particulier ou l\u2019organisation a d\u00e9j\u00e0 b\u00e9n\u00e9fici\u00e9 d\u2019un financement, il ou elle a rempli avec succ\u00e8s les d\u00e9clarations requises dans les d\u00e9lais impartis.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La priorit\u00e9 peut \u00eatre accord\u00e9e aux activit\u00e9s se d\u00e9roulant dans des contextes o\u00f9 le chiffrement est un enjeu public ou politique actif, et o\u00f9 l\u2019\u00e9v\u00e9nement peut contribuer de mani\u00e8re constructive au dialogue local.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Financement<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le cycle 2026, la Fondation Internet Society pr\u00e9voit d\u2019attribuer 22 \u00e0 28 subventions d\u2019un montant moyen de 3 000 dollars am\u00e9ricains chacune.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Accessibilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation Internet Society s\u2019engage \u00e0 soutenir des \u00e9v\u00e9nements favorisant une participation large et \u00e9quitable. Nous encourageons les organisateurs \u00e0 int\u00e9grer l\u2019accessibilit\u00e9 et l\u2019inclusion d\u00e8s le d\u00e9part et \u00e0 demander une assistance suppl\u00e9mentaire si elle peut am\u00e9liorer de mani\u00e8re significative la participation et l\u2019acc\u00e8s. Les prestations \u00e0 pr\u00e9voir sont par exemple la traduction et l\u2019interpr\u00e9tation, l\u2019accessibilit\u00e9 physique ou visuelle, ainsi qu\u2019une aide ou des bourses pour les participants exclus de ce type d\u2019\u00e9v\u00e9nements pour un motif financier (par exemple, frais de garde d\u2019enfants, etc.).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9claration<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les quatre semaines suivant l\u2019\u00e9v\u00e9nement, les b\u00e9n\u00e9ficiaires doivent soumettre des d\u00e9clarations narratives et budg\u00e9taires via Fluxx. Ces d\u00e9clarations incluent g\u00e9n\u00e9ralement un r\u00e9sum\u00e9 de l\u2019\u00e9v\u00e9nement, des informations sur la participation\/fr\u00e9quentation, ainsi que des points importants (par exemple, t\u00e9moignages, liens ou autres documents).<\/p>\n\n\n\n<div class=\"wp-block-cover is-light\" style=\"min-height:258px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-fl-header-hover-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Comment poser sa candidature<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les candidatures seront accept\u00e9es du <strong>23 juin au 24 juillet \u00e0 21 h 00 UTC<\/strong> et devront \u00eatre soumises en ligne via Fluxx, la <a href=\"https:\/\/isocfoundation.fluxx.io\/user_sessions\/new\">plateforme de gestion des subventions de la Fondation Internet Society<\/a>. Les candidatures incompl\u00e8tes ou non conformes aux crit\u00e8res d&rsquo;\u00e9ligibilit\u00e9 ne seront pas prises en compte. <strong>Les candidats doivent \u00eatre inscrits sur Fluxx au moins 24 heures avant la date limite de d\u00e9p\u00f4t des candidatures<\/strong>, et les candidatures doivent \u00eatre soumises avant cette date limite pour pouvoir pr\u00e9tendre \u00e0 un financement. Aucune candidature envoy\u00e9e par e-mail ne sera accept\u00e9e.<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Ressources utiles<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.globalencryption.org\/events\/ged\/ged-2025\/events\/\">\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement 2025<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.internetsociety.org\/fr\/issues\/encryption\/resources\/\">Ressources de l\u2019ISOC sur le chiffrement<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Des questions ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez des questions concernant ce programme ou le processus de candidature, veuillez envoyer un courriel \u00e0 l\u2019adresse suivante : <a href=\"mailto:foundation@isocfoundation.org\">foundation@isocfoundation.org<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9couvrez nos&nbsp;<a href=\"https:\/\/www.isocfoundation.org\/fr\/programmes-de-bourses\/\">domaines de financement<\/a>&nbsp;pour voir comment nous soutenons la communaut\u00e9 Internet mondiale, et souscrivez \u00e0 notre&nbsp;<a href=\"https:\/\/www.isocfoundation.org\/fr\/subscribe\/\">bulletin d\u2019informations<\/a>&nbsp;pour recevoir les derni\u00e8res actualit\u00e9s et annonces concernant nos projets.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le financement des \u00e9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement soutient les activit\u00e9s men\u00e9es par la communaut\u00e9 qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement de bout en bout robuste, aidant les communaut\u00e9s \u00e0 comprendre son importance pour la confidentialit\u00e9, la s\u00e9curit\u00e9 et la confiance, tout en amplifiant l&rsquo;appel mondial \u00e0 prot\u00e9ger et \u00e0 renforcer le chiffrement.<\/p>\n","protected":false},"featured_media":20834,"template":"","application-status":[211],"programme-area":[],"class_list":["post-20827","grant-programme","type-grant-programme","status-publish","has-post-thumbnail","hentry","application-status-ferme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement | Fondation Internet Society<\/title>\n<meta name=\"description\" content=\"Ce financement soutient les activit\u00e9s communautaires qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout \u00e0 l&#039;occasion de la Journ\u00e9e mondiale du chiffrement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement | Fondation Internet Society\" \/>\n<meta property=\"og:description\" content=\"Ce financement soutient les activit\u00e9s communautaires qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout \u00e0 l&#039;occasion de la Journ\u00e9e mondiale du chiffrement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/\" \/>\n<meta property=\"og:site_name\" content=\"Internet Society Foundation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-19T19:56:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2026\/03\/GED-Rwanda-Chapter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ISOC_Foundation\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/\",\"name\":\"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement | Fondation Internet Society\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/GED-Rwanda-Chapter.jpg\",\"datePublished\":\"2026-03-24T09:46:03+00:00\",\"dateModified\":\"2026-08-19T19:56:01+00:00\",\"description\":\"Ce financement soutient les activit\u00e9s communautaires qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout \u00e0 l'occasion de la Journ\u00e9e mondiale du chiffrement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/GED-Rwanda-Chapter.jpg\",\"contentUrl\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/GED-Rwanda-Chapter.jpg\",\"width\":1200,\"height\":801,\"caption\":\"A group of individuals seated at desks, working on computers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/grant-programme\\\/evenements-de-la-journee-mondiale-du-chiffrement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.isocfoundation.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grant Programmes\",\"item\":\"https:\\\/\\\/www.isocfoundation.org\\\/grant-programme\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#website\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/\",\"name\":\"Internet Society Foundation\",\"description\":\"The Internet transforms lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.isocfoundation.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#organization\",\"name\":\"Internet Society Foundation\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/internet-society-foundation.jpg\",\"contentUrl\":\"https:\\\/\\\/www.isocfoundation.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/internet-society-foundation.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Internet Society Foundation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isocfoundation.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ISOC_Foundation\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement | Fondation Internet Society","description":"Ce financement soutient les activit\u00e9s communautaires qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout \u00e0 l'occasion de la Journ\u00e9e mondiale du chiffrement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement | Fondation Internet Society","og_description":"Ce financement soutient les activit\u00e9s communautaires qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout \u00e0 l'occasion de la Journ\u00e9e mondiale du chiffrement.","og_url":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/","og_site_name":"Internet Society Foundation","article_modified_time":"2026-08-19T19:56:01+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2026\/03\/GED-Rwanda-Chapter.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ISOC_Foundation","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/","url":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/","name":"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement | Fondation Internet Society","isPartOf":{"@id":"https:\/\/www.isocfoundation.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/#primaryimage"},"image":{"@id":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2026\/03\/GED-Rwanda-Chapter.jpg","datePublished":"2026-03-24T09:46:03+00:00","dateModified":"2026-08-19T19:56:01+00:00","description":"Ce financement soutient les activit\u00e9s communautaires qui c\u00e9l\u00e8brent et d\u00e9fendent un chiffrement fort de bout en bout \u00e0 l'occasion de la Journ\u00e9e mondiale du chiffrement.","breadcrumb":{"@id":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/#primaryimage","url":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2026\/03\/GED-Rwanda-Chapter.jpg","contentUrl":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2026\/03\/GED-Rwanda-Chapter.jpg","width":1200,"height":801,"caption":"A group of individuals seated at desks, working on computers"},{"@type":"BreadcrumbList","@id":"https:\/\/www.isocfoundation.org\/fr\/grant-programme\/evenements-de-la-journee-mondiale-du-chiffrement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.isocfoundation.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Grant Programmes","item":"https:\/\/www.isocfoundation.org\/grant-programme\/"},{"@type":"ListItem","position":3,"name":"\u00c9v\u00e9nements de la Journ\u00e9e mondiale du chiffrement"}]},{"@type":"WebSite","@id":"https:\/\/www.isocfoundation.org\/#website","url":"https:\/\/www.isocfoundation.org\/","name":"Internet Society Foundation","description":"The Internet transforms lives","publisher":{"@id":"https:\/\/www.isocfoundation.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.isocfoundation.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.isocfoundation.org\/#organization","name":"Internet Society Foundation","url":"https:\/\/www.isocfoundation.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.isocfoundation.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2019\/02\/internet-society-foundation.jpg","contentUrl":"https:\/\/www.isocfoundation.org\/wp-content\/uploads\/2019\/02\/internet-society-foundation.jpg","width":1200,"height":630,"caption":"Internet Society Foundation"},"image":{"@id":"https:\/\/www.isocfoundation.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ISOC_Foundation"]}]}},"_links":{"self":[{"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/grant-programme\/20827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/grant-programme"}],"about":[{"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/types\/grant-programme"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/media\/20834"}],"wp:attachment":[{"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/media?parent=20827"}],"wp:term":[{"taxonomy":"application-status","embeddable":true,"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/application-status?post=20827"},{"taxonomy":"programme-area","embeddable":true,"href":"https:\/\/www.isocfoundation.org\/fr\/wp-json\/wp\/v2\/programme-area?post=20827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}